{"id":29315,"date":"2016-11-14T14:12:28","date_gmt":"2016-11-14T13:12:28","guid":{"rendered":"https:\/\/abbruch2020.indermache.de\/verband\/partner\/"},"modified":"2025-07-07T07:40:29","modified_gmt":"2025-07-07T05:40:29","slug":"partner","status":"publish","type":"page","link":"https:\/\/www.deutscher-abbruchverband.de\/en\/verband\/partner\/","title":{"rendered":"Partners"},"content":{"rendered":"<h2>Safety and Health protection at the workplace<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Safety and Health protection at the workplace<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":26133,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"tags":[3721,3979],"class_list":["post-29315","page","type-page","status-publish","hentry","tag-health-and-safety-protection","tag-partner-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Partners - Deutscher Abbruchverband e.V.<\/title>\n<meta name=\"description\" content=\"Die Partner des Deutschen Abbruchverbandes in den Bereichen Arbeitsschutz, Aus- und Weiterbildung, sowie Verb\u00e4nde, mit denen der DA kooperiert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deutscher-abbruchverband.de\/en\/verband\/partner\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partners - Deutscher Abbruchverband e.V.\" \/>\n<meta property=\"og:description\" content=\"Die Partner des Deutschen Abbruchverbandes in den Bereichen Arbeitsschutz, Aus- und Weiterbildung, sowie Verb\u00e4nde, mit denen der DA kooperiert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deutscher-abbruchverband.de\/en\/verband\/partner\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutscher Abbruchverband e.V.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pg\/Deutscher-Abbruchverband-eV-163906820357873\/about\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T05:40:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deutscher-abbruchverband.de\\\/en\\\/verband\\\/partner\\\/\",\"url\":\"https:\\\/\\\/www.deutscher-abbruchverband.de\\\/en\\\/verband\\\/partner\\\/\",\"name\":\"Partners - Deutscher Abbruchverband e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deutscher-abbruchverband.de\\\/#website\"},\"datePublished\":\"2016-11-14T13:12:28+00:00\",\"dateModified\":\"2025-07-07T05:40:29+00:00\",\"description\":\"Die Partner des Deutschen Abbruchverbandes in den Bereichen Arbeitsschutz, Aus- und Weiterbildung, sowie Verb\u00e4nde, mit denen der DA kooperiert.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deutscher-abbruchverband.de\\\/en\\\/verband\\\/partner\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deutscher-abbruchverband.de\\\/en\\\/verband\\\/partner\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deutscher-abbruchverband.de\\\/en\\\/verband\\\/partner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.deutscher-abbruchverband.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Association\",\"item\":\"https:\\\/\\\/www.deutscher-abbruchverband.de\\\/en\\\/verband\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Partners\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deutscher-abbruchverband.de\\\/#website\",\"url\":\"https:\\\/\\\/www.deutscher-abbruchverband.de\\\/\",\"name\":\"Deutscher Abbruchverband e.V.\",\"description\":\"Oberl\u00e4nder Ufer 180 - 182  50968 K\u00f6ln\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deutscher-abbruchverband.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Partners - Deutscher Abbruchverband e.V.","description":"Die Partner des Deutschen Abbruchverbandes in den Bereichen Arbeitsschutz, Aus- und Weiterbildung, sowie Verb\u00e4nde, mit denen der DA kooperiert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deutscher-abbruchverband.de\/en\/verband\/partner\/","og_locale":"en_US","og_type":"article","og_title":"Partners - Deutscher Abbruchverband e.V.","og_description":"Die Partner des Deutschen Abbruchverbandes in den Bereichen Arbeitsschutz, Aus- und Weiterbildung, sowie Verb\u00e4nde, mit denen der DA kooperiert.","og_url":"https:\/\/www.deutscher-abbruchverband.de\/en\/verband\/partner\/","og_site_name":"Deutscher Abbruchverband e.V.","article_publisher":"https:\/\/www.facebook.com\/pg\/Deutscher-Abbruchverband-eV-163906820357873\/about\/","article_modified_time":"2025-07-07T05:40:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.deutscher-abbruchverband.de\/en\/verband\/partner\/","url":"https:\/\/www.deutscher-abbruchverband.de\/en\/verband\/partner\/","name":"Partners - Deutscher Abbruchverband e.V.","isPartOf":{"@id":"https:\/\/www.deutscher-abbruchverband.de\/#website"},"datePublished":"2016-11-14T13:12:28+00:00","dateModified":"2025-07-07T05:40:29+00:00","description":"Die Partner des Deutschen Abbruchverbandes in den Bereichen Arbeitsschutz, Aus- und Weiterbildung, sowie Verb\u00e4nde, mit denen der DA kooperiert.","breadcrumb":{"@id":"https:\/\/www.deutscher-abbruchverband.de\/en\/verband\/partner\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deutscher-abbruchverband.de\/en\/verband\/partner\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.deutscher-abbruchverband.de\/en\/verband\/partner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.deutscher-abbruchverband.de\/en\/"},{"@type":"ListItem","position":2,"name":"Association","item":"https:\/\/www.deutscher-abbruchverband.de\/en\/verband\/"},{"@type":"ListItem","position":3,"name":"Partners"}]},{"@type":"WebSite","@id":"https:\/\/www.deutscher-abbruchverband.de\/#website","url":"https:\/\/www.deutscher-abbruchverband.de\/","name":"Deutscher Abbruchverband e.V.","description":"Oberl\u00e4nder Ufer 180 - 182  50968 K\u00f6ln","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deutscher-abbruchverband.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.deutscher-abbruchverband.de\/en\/wp-json\/wp\/v2\/pages\/29315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deutscher-abbruchverband.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.deutscher-abbruchverband.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.deutscher-abbruchverband.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deutscher-abbruchverband.de\/en\/wp-json\/wp\/v2\/comments?post=29315"}],"version-history":[{"count":3,"href":"https:\/\/www.deutscher-abbruchverband.de\/en\/wp-json\/wp\/v2\/pages\/29315\/revisions"}],"predecessor-version":[{"id":55439,"href":"https:\/\/www.deutscher-abbruchverband.de\/en\/wp-json\/wp\/v2\/pages\/29315\/revisions\/55439"}],"up":[{"embeddable":true,"href":"https:\/\/www.deutscher-abbruchverband.de\/en\/wp-json\/wp\/v2\/pages\/26133"}],"wp:attachment":[{"href":"https:\/\/www.deutscher-abbruchverband.de\/en\/wp-json\/wp\/v2\/media?parent=29315"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deutscher-abbruchverband.de\/en\/wp-json\/wp\/v2\/tags?post=29315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}